{"id":21490,"date":"2022-07-13T11:24:49","date_gmt":"2022-07-13T11:24:49","guid":{"rendered":"https:\/\/www.pro-contact.nl\/?post_type=klantcase&#038;p=21490"},"modified":"2025-07-15T12:38:14","modified_gmt":"2025-07-15T12:38:14","slug":"totality","status":"publish","type":"klantcase","link":"https:\/\/www.pro-contact.nl\/en\/klantcase\/totality\/","title":{"rendered":"Totality"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;80&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;12&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h2>Curious about the effects of job marketing? Have a look at Totality!<\/h2>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<strong>Totality<\/strong> showed how magical the effects can be when you combine job marketing and recruitment: they hired <strong>5<\/strong> new colleagues with a CPH of <strong>\u20ac 4.080.<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f6f6f6&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; bottom_padding=&#8221;100&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; class=&#8221;resultaten-row&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text el_class=&#8221;resultaten&#8221;]\n<h2 aria-hidden=\"true\">Results<\/h2>\n[\/vc_column_text][vc_column_text el_class=&#8221;resultaat-blok&#8221;]Applicants<\/p>\n<p class=\"cijfer\">18<\/p>\n[\/vc_column_text][vc_column_text el_class=&#8221;resultaat-blok&#8221;]Cost per applicant<\/p>\n<p class=\"cijfer\">\u20ac 9,61<\/p>\n[\/vc_column_text][vc_column_text el_class=&#8221;resultaat-blok&#8221;]Hires<\/p>\n<p class=\"cijfer\">5<\/p>\n[\/vc_column_text][vc_column_text el_class=&#8221;resultaat-blok&#8221;]Cost per hire<\/p>\n<p class=\"cijfer\">\u20ac 4.080<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<div class=\"klantcase-visual-container\"><img decoding=\"async\" class=\"klantcase-visual\" src=\"https:\/\/www.pro-contact.nl\/wp-content\/uploads\/2022\/07\/Cases_Totality.png\" \/><video autoplay=\"autoplay\" loop=\"loop\" muted=\"\" width=\"300\" height=\"150\" data-mce-fragment=\"1\"><source src=\"\" type=\"video\/mp4\" \/><\/video><\/div>\n[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#ffffff&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;80&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; zindex=&#8221;12&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-10-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;right&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243;&#8230;<\/p>\n","protected":false},"featured_media":20537,"template":"","categories":[],"tags":[],"klantcase-categorie":[103,94],"klantcase-dienst":[],"class_list":["post-21490","klantcase","type-klantcase","status-publish","has-post-thumbnail","klantcase-categorie-dienstverlening-uitgelicht-en","klantcase-categorie-business-services","","en","wp-json","wp","v2","21490"],"_links":{"self":[{"href":"https:\/\/www.pro-contact.nl\/en\/wp-json\/wp\/v2\/klantcase\/21490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pro-contact.nl\/en\/wp-json\/wp\/v2\/klantcase"}],"about":[{"href":"https:\/\/www.pro-contact.nl\/en\/wp-json\/wp\/v2\/types\/klantcase"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pro-contact.nl\/en\/wp-json\/wp\/v2\/media\/20537"}],"wp:attachment":[{"href":"https:\/\/www.pro-contact.nl\/en\/wp-json\/wp\/v2\/media?parent=21490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pro-contact.nl\/en\/wp-json\/wp\/v2\/categories?post=21490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pro-contact.nl\/en\/wp-json\/wp\/v2\/tags?post=21490"},{"taxonomy":"klantcase-categorie","embeddable":true,"href":"https:\/\/www.pro-contact.nl\/en\/wp-json\/wp\/v2\/klantcase-categorie?post=21490"},{"taxonomy":"klantcase-dienst","embeddable":true,"href":"https:\/\/www.pro-contact.nl\/en\/wp-json\/wp\/v2\/klantcase-dienst?post=21490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}